{"id":600,"date":"2020-07-20T10:04:22","date_gmt":"2020-07-20T08:04:22","guid":{"rendered":"https:\/\/www.espace-sante-bersim.fr\/?page_id=600"},"modified":"2020-07-20T10:04:22","modified_gmt":"2020-07-20T08:04:22","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.espace-sante-bersim.fr\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f599-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"599\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/600#wpcf7-f599-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"599\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f599-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> NOM (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><label>Pr\u00e9nom (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre adresse de messagerie (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p>Motif de la demande : <span class=\"wpcf7-form-control-wrap\" data-name=\"motif\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"motif\"><option value=\"\">&#8212;Veuillez choisir une option&#8212;<\/option><option value=\"Location cabinet\">Location cabinet<\/option><option value=\"Autre\">Autre<\/option><\/select><\/span>\n<\/p>\n<p><label>Commentaires<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-commentaires\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"textarea-commentaires\"><\/textarea><\/span> <\/label>\n<\/p>\n<p>Joindre un document : <span class=\"wpcf7-form-control-wrap\" data-name=\"file-569\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-569\" \/><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-600","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/pages\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":1,"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/pages\/600\/revisions"}],"predecessor-version":[{"id":601,"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/pages\/600\/revisions\/601"}],"wp:attachment":[{"href":"https:\/\/www.espace-sante-bersim.fr\/index.php\/wp-json\/wp\/v2\/media?parent=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}